{"id":97539,"date":"2023-08-14T19:15:51","date_gmt":"2023-08-14T17:15:51","guid":{"rendered":"https:\/\/www.jmf-filters.com\/sobre-nos\/"},"modified":"2025-03-06T11:26:19","modified_gmt":"2025-03-06T10:26:19","slug":"sobre-nos","status":"publish","type":"page","link":"https:\/\/www.jmf-filters.com\/pt-pt\/sobre-nos\/","title":{"rendered":"Sobre n\u00f3s"},"content":{"rendered":"<style>.kadence-column9370_7c5926-ae > .kt-inside-inner-col,.kadence-column9370_7c5926-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column9370_7c5926-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column9370_7c5926-ae > .kt-inside-inner-col{flex-direction:column;}.kadence-column9370_7c5926-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column9370_7c5926-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column9370_7c5926-ae{position:relative;}@media all and (max-width: 1024px){.kadence-column9370_7c5926-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column9370_7c5926-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column9370_7c5926-ae custom_breadcrumbs\"><div class=\"kt-inside-inner-col\"><nav  aria-label=\"breadcrumb\"><ol class=\"breadcrumb\"><li class=\"breadcrumb-item active\" aria-current=\"page\"><span>Homepage<\/span><\/li><\/ol><\/nav>\n<\/div><\/div>\n<style>.kb-row-layout-id9370_cbc232-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id9370_cbc232-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id9370_cbc232-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id9370_cbc232-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id9370_cbc232-b9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id9370_cbc232-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id9370_cbc232-b9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column9370_d901d7-35 > .kt-inside-inner-col,.kadence-column9370_d901d7-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column9370_d901d7-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column9370_d901d7-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column9370_d901d7-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column9370_d901d7-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column9370_d901d7-35{position:relative;}@media all and (max-width: 1024px){.kadence-column9370_d901d7-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column9370_d901d7-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column9370_d901d7-35\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading9370_85bbc6-b7, .wp-block-kadence-advancedheading.kt-adv-heading9370_85bbc6-b7[data-kb-block=\"kb-adv-heading9370_85bbc6-b7\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading9370_85bbc6-b7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading9370_85bbc6-b7[data-kb-block=\"kb-adv-heading9370_85bbc6-b7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading9370_85bbc6-b7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading9370_85bbc6-b7[data-kb-block=\"kb-adv-heading9370_85bbc6-b7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading9370_85bbc6-b7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading9370_85bbc6-b7\">Sobre n\u00f3s<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Com mais de tr\u00eas d\u00e9cadas de experi\u00eancia em filtragem de l\u00edquidos, a JMF Filters B.V. \u00e9 a tua solu\u00e7\u00e3o para servi\u00e7os de desonera\u00e7\u00e3o e orientados para a solu\u00e7\u00e3o. A nossa empresa \u00e9 especializada na produ\u00e7\u00e3o, consultoria e com\u00e9rcio de solu\u00e7\u00f5es de filtragem personalizadas, adaptadas \u00e0s necessidades espec\u00edficas dos clientes. <br\/><br\/>A nossa \u00e1rea de especializa\u00e7\u00e3o abrange o aconselhamento, o fabrico e o fornecimento de filtros de l\u00edquidos industriais adequados para filtrar \u00e1guas subterr\u00e2neas, \u00e1guas de processo, \u00e1guas superficiais, \u00e1guas residuais, bem como fluidos qu\u00edmicos e m\u00e9dicos. Tamb\u00e9m fornecemos para as ind\u00fastrias de petr\u00f3leo e g\u00e1s, alimentar, offshore, farmac\u00eautica e outras. <br\/><br\/>Com mais de 30 anos de experi\u00eancia no aconselhamento e venda de produtos de filtragem, a JMF Filters B.V. estabeleceu uma forte reputa\u00e7\u00e3o de fiabilidade, servi\u00e7o superior e pre\u00e7os competitivos. Os nossos produtos de filtragem de alta qualidade conquistaram-nos uma vasta base de clientes que apreciam a nossa dedica\u00e7\u00e3o \u00e0 excel\u00eancia. <br\/><br\/>Gra\u00e7as \u00e0 nossa produ\u00e7\u00e3o interna e aos acordos de pre\u00e7os favor\u00e1veis com parceiros, fabricantes e fornecedores de confian\u00e7a, juntamente com a nossa extensa capacidade de armazenamento, podemos fornecer prontamente quase todos os tipos de filtros de l\u00edquidos.<br\/><br\/><strong>A JMF Filters B.V. \u00e9 o teu parceiro de confian\u00e7a na filtragem de l\u00edquidos, com a nossa equipa dispon\u00edvel 24 horas por dia, 7 dias por semana, para te ajudar.<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column9370_527d78-a7 > .kt-inside-inner-col,.kadence-column9370_527d78-a7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column9370_527d78-a7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column9370_527d78-a7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column9370_527d78-a7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column9370_527d78-a7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column9370_527d78-a7{position:relative;}@media all and (max-width: 1024px){.kadence-column9370_527d78-a7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column9370_527d78-a7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column9370_527d78-a7\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bedrijfsfilm - JMF-Filters B.V.\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/T80Q_erp0iA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id9370_85385f-32 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id9370_85385f-32 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id9370_85385f-32 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id9370_85385f-32 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id9370_85385f-32 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id9370_85385f-32 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id9370_85385f-32 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column9370_a2b627-49 > .kt-inside-inner-col,.kadence-column9370_a2b627-49 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column9370_a2b627-49 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column9370_a2b627-49 > .kt-inside-inner-col{flex-direction:column;}.kadence-column9370_a2b627-49 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column9370_a2b627-49 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column9370_a2b627-49{position:relative;}@media all and (max-width: 1024px){.kadence-column9370_a2b627-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column9370_a2b627-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column9370_a2b627-49\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading9370_77f8b2-99, .wp-block-kadence-advancedheading.kt-adv-heading9370_77f8b2-99[data-kb-block=\"kb-adv-heading9370_77f8b2-99\"]{font-style:normal;color:#1f2c73;}.wp-block-kadence-advancedheading.kt-adv-heading9370_77f8b2-99 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading9370_77f8b2-99[data-kb-block=\"kb-adv-heading9370_77f8b2-99\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading9370_77f8b2-99 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading9370_77f8b2-99[data-kb-block=\"kb-adv-heading9370_77f8b2-99\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading9370_77f8b2-99 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading9370_77f8b2-99\">A nossa equipa<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A JMF Filters B.V. pretende ser um fornecedor empenhado e est\u00e1vel para os seus clientes, que tamb\u00e9m os acompanha a longo prazo. Distinguimo-nos por um servi\u00e7o bom e r\u00e1pido, fiabilidade, pre\u00e7os competitivos, prazos de entrega curtos e capacidade de pensar em conjunto com o cliente. Os nossos objectivos s\u00e3o a rapidez, o servi\u00e7o, a desresponsabiliza\u00e7\u00e3o, o conhecimento, a qualidade, o aconselhamento e o trabalho personalizado, a orienta\u00e7\u00e3o para o servi\u00e7o, a paix\u00e3o, a flexibilidade e a continuidade A JMF-Filters B.V. tamb\u00e9m quer ser um fornecedor est\u00e1vel e envolvido para os seus clientes no futuro. Seguran\u00e7a, sa\u00fade, bem-estar e respeito pelo ambiente.   <\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column9370_0715fd-e1 > .kt-inside-inner-col,.kadence-column9370_0715fd-e1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column9370_0715fd-e1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column9370_0715fd-e1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column9370_0715fd-e1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column9370_0715fd-e1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column9370_0715fd-e1{position:relative;}@media all and (max-width: 1024px){.kadence-column9370_0715fd-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column9370_0715fd-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column9370_0715fd-e1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading9370_b4c045-2c, .wp-block-kadence-advancedheading.kt-adv-heading9370_b4c045-2c[data-kb-block=\"kb-adv-heading9370_b4c045-2c\"]{font-style:normal;color:#1f2c73;}.wp-block-kadence-advancedheading.kt-adv-heading9370_b4c045-2c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading9370_b4c045-2c[data-kb-block=\"kb-adv-heading9370_b4c045-2c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading9370_b4c045-2c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading9370_b4c045-2c[data-kb-block=\"kb-adv-heading9370_b4c045-2c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading9370_b4c045-2c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading9370_b4c045-2c\">Patroc\u00ednios e institui\u00e7\u00f5es de caridade:<\/h4>\n\n\n\n<div class=\"wp-block-stackable-carousel stk-block-carousel stk--is-slide stk--arrows-justify-space-between stk--arrows-align-center stk-block stk-e59f306\" data-slides-to-show=\"3\" data-block-id=\"e59f306\"><style>.stk-e59f306{--slides-to-show:3 !important;--gap:0px !important}@media screen and (max-width:1023px){.stk-e59f306{--slides-to-show:2 !important}}@media screen and (max-width:767px){.stk-e59f306{--slides-to-show:2 !important}}<\/style><div class=\"stk-block-carousel__content-wrapper\"><div class=\"stk-row stk-inner-blocks stk-block-content stk-block-carousel__slider-wrapper stk-content-align stk-e59f306-column\"><div class=\"stk-block-carousel__slider\" role=\"list\" data-autoplay=\"2500\" data-label-slide-of=\"Slide %%d of %%d\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-3350972\" data-v=\"4\" data-block-id=\"3350972\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-3350972-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-3350972-inner-blocks\"><style>.kb-image9370_72a268-bb .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_72a268-bb\"><img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/beets-festival.jpg\" alt=\"\" class=\"kb-img wp-image-42707\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/beets-festival.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/beets-festival-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-3ecd283\" data-v=\"4\" data-block-id=\"3ecd283\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-3ecd283-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-3ecd283-inner-blocks\"><style>.kb-image9370_28f63f-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_28f63f-55\"><img alt=\"Brooke organization humanitarian logo\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/brooke.jpg\" alt=\"\" class=\"kb-img wp-image-42714\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/brooke.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/brooke-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-b21af87\" data-v=\"4\" data-block-id=\"b21af87\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-b21af87-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-b21af87-inner-blocks\"><style>.kb-image9370_ffd1c4-fe .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_ffd1c4-fe\"><img alt=\"Dierenambulance animal rescue logo\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/dierenambulance.jpg\" alt=\"\" class=\"kb-img wp-image-42721\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/dierenambulance.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/dierenambulance-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-b7acf51\" data-v=\"4\" data-block-id=\"b7acf51\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-b7acf51-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-b7acf51-inner-blocks\"><style>.kb-image9370_cef523-e5 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_cef523-e5\"><img alt=\"Harvest Moon brand logo design\" loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/harvest-moon.jpg\" alt=\"\" class=\"kb-img wp-image-42728\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/harvest-moon.jpg 408w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/harvest-moon-300x92.jpg 300w\" sizes=\"auto, (max-width: 408px) 100vw, 408px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-b51e801\" data-v=\"4\" data-block-id=\"b51e801\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-b51e801-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-b51e801-inner-blocks\"><style>.kb-image9370_f3b113-0f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_f3b113-0f\"><img alt=\"KiKa childhood cancer foundation logo\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/kika.jpg\" alt=\"\" class=\"kb-img wp-image-42735\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/kika.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/kika-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-33c6c53\" data-v=\"4\" data-block-id=\"33c6c53\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-33c6c53-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-33c6c53-inner-blocks\"><style>.kb-image9370_379c0b-69 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_379c0b-69\"><img alt=\"Madjoe brand logo in horizontal layout\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/madjoe.jpg\" alt=\"\" class=\"kb-img wp-image-42742\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/madjoe.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/madjoe-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-18e5b47\" data-v=\"4\" data-block-id=\"18e5b47\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-18e5b47-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-18e5b47-inner-blocks\"><style>.kb-image9370_5cd918-64 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_5cd918-64\"><img alt=\"Natuurmonument conservation organization logo\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/natuurmonument.jpg\" alt=\"\" class=\"kb-img wp-image-42749\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/natuurmonument.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/natuurmonument-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-680771e\" data-v=\"4\" data-block-id=\"680771e\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-680771e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-680771e-inner-blocks\"><style>.kb-image9370_7b9e82-3e .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_7b9e82-3e\"><img alt=\"Project Hope humanitarian organization logo\" loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/project-hope.jpg\" alt=\"\" class=\"kb-img wp-image-42756\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/project-hope.jpg 408w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/project-hope-300x92.jpg 300w\" sizes=\"auto, (max-width: 408px) 100vw, 408px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-5a210ac\" data-v=\"4\" data-block-id=\"5a210ac\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-5a210ac-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-5a210ac-inner-blocks\"><style>.kb-image9370_9aef44-21 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_9aef44-21\"><img alt=\"Stichting AAP nonprofit organization logo\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/stichting-aap.jpg\" alt=\"\" class=\"kb-img wp-image-42763\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/stichting-aap.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/stichting-aap-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-df6bbb6\" data-v=\"4\" data-block-id=\"df6bbb6\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-df6bbb6-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-df6bbb6-inner-blocks\"><style>.kb-image9370_6dccd0-6a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_6dccd0-6a\"><img alt=\"Westfrisia corporate logo design\" loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/westfrisia.jpg\" alt=\"\" class=\"kb-img wp-image-42770\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/westfrisia.jpg 408w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/westfrisia-300x92.jpg 300w\" sizes=\"auto, (max-width: 408px) 100vw, 408px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-41dae22\" data-v=\"4\" data-block-id=\"41dae22\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-41dae22-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-41dae22-inner-blocks\"><style>.kb-image9370_467dee-ef .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image9370_467dee-ef size-full\"><img alt=\"WNF organization logo in landscape format\" loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"125\" src=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/wnf.jpg\" alt=\"\" class=\"kb-img wp-image-42777\" srcset=\"https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/wnf.jpg 407w, https:\/\/www.jmf-filters.com\/wp-content\/uploads\/2023\/12\/wnf-300x92.jpg 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Sobre n\u00f3s Com mais de tr\u00eas d\u00e9cadas de experi\u00eancia em filtragem de l\u00edquidos, a JMF Filters B.V. \u00e9 a tua solu\u00e7\u00e3o para servi\u00e7os de desonera\u00e7\u00e3o e orientados para a solu\u00e7\u00e3o. A nossa empresa \u00e9 especializada na produ\u00e7\u00e3o, consultoria e com\u00e9rcio de solu\u00e7\u00f5es de filtragem personalizadas, adaptadas \u00e0s necessidades espec\u00edficas dos clientes. A nossa \u00e1rea de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-97539","page","type-page","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Lars Fledderus","author_link":"https:\/\/www.jmf-filters.com\/pt-pt\/author\/lars\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/pages\/97539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=97539"}],"version-history":[{"count":1,"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/pages\/97539\/revisions"}],"predecessor-version":[{"id":97552,"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/pages\/97539\/revisions\/97552"}],"wp:attachment":[{"href":"https:\/\/www.jmf-filters.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=97539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}